{"id":20463,"date":"2020-10-21T13:06:17","date_gmt":"2020-10-21T11:06:17","guid":{"rendered":"https:\/\/www.oska.com\/?post_type=stores&#038;p=20463"},"modified":"2025-04-24T13:50:37","modified_gmt":"2025-04-24T11:50:37","slug":"oska-haarlem","status":"publish","type":"stores","link":"https:\/\/www.oska.com\/nl\/stores\/oska-haarlem\/","title":{"rendered":"Haarlem"},"featured_media":16064,"template":"","oska_city":[3288],"oska_country":[3260],"class_list":["post-20463","stores","type-stores","status-publish","has-post-thumbnail","oska_city-haarlem","oska_country-nl"],"_links":{"self":[{"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/stores\/20463","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/stores"}],"about":[{"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/types\/stores"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/media\/16064"}],"wp:attachment":[{"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/media?parent=20463"}],"wp:term":[{"taxonomy":"oska_city","embeddable":true,"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/oska_city?post=20463"},{"taxonomy":"oska_country","embeddable":true,"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/oska_country?post=20463"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}