{"id":17708,"date":"2020-08-20T16:07:25","date_gmt":"2020-08-20T14:07:25","guid":{"rendered":"https:\/\/www.oska.com\/?post_type=stores&#038;p=17708"},"modified":"2025-04-29T10:24:31","modified_gmt":"2025-04-29T08:24:31","slug":"oska-regensburg","status":"publish","type":"stores","link":"https:\/\/www.oska.com\/nl\/stores\/oska-regensburg\/","title":{"rendered":"Regensburg"},"featured_media":74429,"template":"","oska_city":[3307],"oska_country":[3257],"class_list":["post-17708","stores","type-stores","status-publish","has-post-thumbnail","oska_city-regensburg","oska_country-de"],"_links":{"self":[{"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/stores\/17708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/stores"}],"about":[{"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/types\/stores"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/media\/74429"}],"wp:attachment":[{"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/media?parent=17708"}],"wp:term":[{"taxonomy":"oska_city","embeddable":true,"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/oska_city?post=17708"},{"taxonomy":"oska_country","embeddable":true,"href":"https:\/\/www.oska.com\/nl\/wp-json\/wp\/v2\/oska_country?post=17708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}