{"id":17564,"date":"2020-08-17T11:08:53","date_gmt":"2020-08-17T09:08:53","guid":{"rendered":"https:\/\/www.oska.com\/?post_type=stores&#038;p=17564"},"modified":"2026-09-02T10:00:29","modified_gmt":"2026-09-02T08:00:29","slug":"oska-hannover","status":"publish","type":"stores","link":"https:\/\/www.oska.com\/cs\/stores\/oska-hannover\/","title":{"rendered":"Hannover"},"featured_media":20901,"template":"","oska_city":[3290],"oska_country":[3257],"class_list":["post-17564","stores","type-stores","status-publish","has-post-thumbnail","oska_city-hannover","oska_country-de"],"_links":{"self":[{"href":"https:\/\/www.oska.com\/cs\/wp-json\/wp\/v2\/stores\/17564","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oska.com\/cs\/wp-json\/wp\/v2\/stores"}],"about":[{"href":"https:\/\/www.oska.com\/cs\/wp-json\/wp\/v2\/types\/stores"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oska.com\/cs\/wp-json\/wp\/v2\/media\/20901"}],"wp:attachment":[{"href":"https:\/\/www.oska.com\/cs\/wp-json\/wp\/v2\/media?parent=17564"}],"wp:term":[{"taxonomy":"oska_city","embeddable":true,"href":"https:\/\/www.oska.com\/cs\/wp-json\/wp\/v2\/oska_city?post=17564"},{"taxonomy":"oska_country","embeddable":true,"href":"https:\/\/www.oska.com\/cs\/wp-json\/wp\/v2\/oska_country?post=17564"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}